{"id":187655,"date":"2024-07-31T11:00:39","date_gmt":"2024-07-31T14:00:39","guid":{"rendered":"https:\/\/www.vagasrio.com.br\/?p=187655"},"modified":"2024-07-31T11:00:39","modified_gmt":"2024-07-31T14:00:39","slug":"atendente-de-lanchonete-rio-de-janeiro-rj-18","status":"publish","type":"post","link":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/07\/31\/atendente-de-lanchonete-rio-de-janeiro-rj-18\/","title":{"rendered":"Atendente de Lanchonete &#8211; Rio de Janeiro &#8211; RJ"},"content":{"rendered":"<p style=\"text-align: justify;\">Requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ensino M\u00e9dio Completo;<\/li>\n<li>Ter experi\u00eancia m\u00ednima em restaurantes fast food;<\/li>\n<li>Ser\u00e1 um diferencial ter trabalhado com pastel e cachorro-quente prensado;<\/li>\n<li>Imprescind\u00edvel residir pr\u00f3ximo a Marechal Hermes;<\/li>\n<li>Desej\u00e1vel ter Proatividade, esp\u00edrito de equipe, \u00e1gil, pontual<\/li>\n<li>Solucionador de Conflitos; Emp\u00e1tico<\/li>\n<li>Comprometido e Ass\u00edduo<\/li>\n<li>Disponibilidade de hor\u00e1rio e in\u00edcio imediato.<\/li>\n<li>Contrata\u00e7\u00e3o: CLT<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Descri\u00e7\u00e3o da Vaga:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Atendimento ao p\u00fablico de forma online e presencial;<\/li>\n<li>Libera\u00e7\u00e3o de pedidos a Motoboys e clientes;<\/li>\n<li>Reabastecimento, organiza\u00e7\u00e3o e aux\u00edlio no controle de estoque;<\/li>\n<li>Preparo de lanches e petiscos na chapa e fritadeira;<\/li>\n<li>Limpeza e conserva\u00e7\u00e3o da loja;<\/li>\n<li>Abertura e fechamento de loja e caixa.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de Trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Escala 6\u00d71<\/li>\n<li>De Ter\u00e7a a Domingo de 16:20 \u00e0s 00:20.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Sal\u00e1rio:<\/p>\n<ul style=\"text-align: justify;\">\n<li>R$ 1.560,00<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>VT, VA (R$ 150,00 mensais) e Adicional Noturno<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Local: Marechal Hermes \u2013 Rio de Janeiro<\/p>\n<p style=\"text-align: justify;\">Enviar curr\u00edculo informando no assunto do e-mail a vaga de interesse para <a href=\"mailto:ck.consultoriaderh@gmail.com\">ck.consultoriaderh@gmail.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Requisitos: Ensino M\u00e9dio Completo; Ter experi\u00eancia m\u00ednima em restaurantes fast food; Ser\u00e1 um diferencial ter trabalhado com pastel e cachorro-quente prensado; Imprescind\u00edvel residir pr\u00f3ximo a [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,59],"tags":[],"class_list":["post-187655","post","type-post","status-publish","format-standard","hentry","category-recepcionista-telefonista","category-ensino-medio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atendente de Lanchonete - Rio de Janeiro - RJ - VagasRIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasrio.com.br\/index.php\/2024\/07\/31\/atendente-de-lanchonete-rio-de-janeiro-rj-18\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atendente de Lanchonete - Rio de Janeiro - RJ - VagasRIO\" \/>\n<meta property=\"og:description\" content=\"Requisitos: Ensino M\u00e9dio Completo; Ter experi\u00eancia m\u00ednima em restaurantes fast food; Ser\u00e1 um diferencial ter trabalhado com pastel e cachorro-quente prensado; Imprescind\u00edvel residir pr\u00f3ximo a [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasrio.com.br\/index.php\/2024\/07\/31\/atendente-de-lanchonete-rio-de-janeiro-rj-18\/\" \/>\n<meta property=\"og:site_name\" content=\"VagasRIO\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-31T14:00:39+00:00\" \/>\n<meta name=\"author\" content=\"vagasemprego\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vagasemprego\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2024\\\/07\\\/31\\\/atendente-de-lanchonete-rio-de-janeiro-rj-18\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2024\\\/07\\\/31\\\/atendente-de-lanchonete-rio-de-janeiro-rj-18\\\/\"},\"author\":{\"name\":\"vagasemprego\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#\\\/schema\\\/person\\\/c11a3c03d007680d42e30222eff1ea53\"},\"headline\":\"Atendente de Lanchonete &#8211; Rio de Janeiro &#8211; RJ\",\"datePublished\":\"2024-07-31T14:00:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2024\\\/07\\\/31\\\/atendente-de-lanchonete-rio-de-janeiro-rj-18\\\/\"},\"wordCount\":170,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#organization\"},\"articleSection\":[\"atendimento e recep\u00e7\u00e3o\",\"ensino m\u00e9dio\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2024\\\/07\\\/31\\\/atendente-de-lanchonete-rio-de-janeiro-rj-18\\\/\",\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2024\\\/07\\\/31\\\/atendente-de-lanchonete-rio-de-janeiro-rj-18\\\/\",\"name\":\"Atendente de Lanchonete - Rio de Janeiro - RJ - VagasRIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#website\"},\"datePublished\":\"2024-07-31T14:00:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2024\\\/07\\\/31\\\/atendente-de-lanchonete-rio-de-janeiro-rj-18\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2024\\\/07\\\/31\\\/atendente-de-lanchonete-rio-de-janeiro-rj-18\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2024\\\/07\\\/31\\\/atendente-de-lanchonete-rio-de-janeiro-rj-18\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasrio.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atendente de Lanchonete &#8211; Rio de Janeiro &#8211; RJ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/\",\"name\":\"VagasRIO\",\"description\":\"Vagas de Emprego e Est\u00e1gio no Rio de Janeiro\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasrio.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#organization\",\"name\":\"VagasRIO\",\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo90.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasrio.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo90.jpg\",\"width\":220,\"height\":90,\"caption\":\"VagasRIO\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#\\\/schema\\\/person\\\/c11a3c03d007680d42e30222eff1ea53\",\"name\":\"vagasemprego\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"vagasemprego\"},\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atendente de Lanchonete - Rio de Janeiro - RJ - VagasRIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/07\/31\/atendente-de-lanchonete-rio-de-janeiro-rj-18\/","og_locale":"pt_BR","og_type":"article","og_title":"Atendente de Lanchonete - Rio de Janeiro - RJ - VagasRIO","og_description":"Requisitos: Ensino M\u00e9dio Completo; Ter experi\u00eancia m\u00ednima em restaurantes fast food; Ser\u00e1 um diferencial ter trabalhado com pastel e cachorro-quente prensado; Imprescind\u00edvel residir pr\u00f3ximo a [...]","og_url":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/07\/31\/atendente-de-lanchonete-rio-de-janeiro-rj-18\/","og_site_name":"VagasRIO","article_published_time":"2024-07-31T14:00:39+00:00","author":"vagasemprego","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vagasemprego","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/07\/31\/atendente-de-lanchonete-rio-de-janeiro-rj-18\/#article","isPartOf":{"@id":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/07\/31\/atendente-de-lanchonete-rio-de-janeiro-rj-18\/"},"author":{"name":"vagasemprego","@id":"https:\/\/www.vagasrio.com.br\/#\/schema\/person\/c11a3c03d007680d42e30222eff1ea53"},"headline":"Atendente de Lanchonete &#8211; Rio de Janeiro &#8211; RJ","datePublished":"2024-07-31T14:00:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/07\/31\/atendente-de-lanchonete-rio-de-janeiro-rj-18\/"},"wordCount":170,"publisher":{"@id":"https:\/\/www.vagasrio.com.br\/#organization"},"articleSection":["atendimento e recep\u00e7\u00e3o","ensino m\u00e9dio"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/07\/31\/atendente-de-lanchonete-rio-de-janeiro-rj-18\/","url":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/07\/31\/atendente-de-lanchonete-rio-de-janeiro-rj-18\/","name":"Atendente de Lanchonete - Rio de Janeiro - RJ - VagasRIO","isPartOf":{"@id":"https:\/\/www.vagasrio.com.br\/#website"},"datePublished":"2024-07-31T14:00:39+00:00","breadcrumb":{"@id":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/07\/31\/atendente-de-lanchonete-rio-de-janeiro-rj-18\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasrio.com.br\/index.php\/2024\/07\/31\/atendente-de-lanchonete-rio-de-janeiro-rj-18\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/07\/31\/atendente-de-lanchonete-rio-de-janeiro-rj-18\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasrio.com.br\/"},{"@type":"ListItem","position":2,"name":"Atendente de Lanchonete &#8211; Rio de Janeiro &#8211; RJ"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasrio.com.br\/#website","url":"https:\/\/www.vagasrio.com.br\/","name":"VagasRIO","description":"Vagas de Emprego e Est\u00e1gio no Rio de Janeiro","publisher":{"@id":"https:\/\/www.vagasrio.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasrio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasrio.com.br\/#organization","name":"VagasRIO","url":"https:\/\/www.vagasrio.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasrio.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasrio.com.br\/wp-content\/uploads\/2025\/06\/cropped-logo90.jpg","contentUrl":"https:\/\/www.vagasrio.com.br\/wp-content\/uploads\/2025\/06\/cropped-logo90.jpg","width":220,"height":90,"caption":"VagasRIO"},"image":{"@id":"https:\/\/www.vagasrio.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasrio.com.br\/#\/schema\/person\/c11a3c03d007680d42e30222eff1ea53","name":"vagasemprego","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"vagasemprego"},"url":"https:\/\/www.vagasrio.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=187655"}],"version-history":[{"count":0,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/187655\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=187655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=187655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=187655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}