{"id":189305,"date":"2024-12-05T16:00:44","date_gmt":"2024-12-05T19:00:44","guid":{"rendered":"https:\/\/www.vagasrio.com.br\/?p=189305"},"modified":"2024-12-05T16:00:44","modified_gmt":"2024-12-05T19:00:44","slug":"vendedor-copacabana-rio-de-janeiro-rj-2","status":"publish","type":"post","link":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/12\/05\/vendedor-copacabana-rio-de-janeiro-rj-2\/","title":{"rendered":"Vendedor \u2013 Copacabana -Rio de Janeiro &#8211; RJ"},"content":{"rendered":"<p style=\"text-align: justify;\">Requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ensino m\u00e9dio;<\/li>\n<li>Experi\u00eancia em vendas;<\/li>\n<li>Ser\u00e1 um diferencial ter atuando do ramo do varejo;<\/li>\n<li>Facilidade de acesso \u00e0 regi\u00e3o.<\/li>\n<li>Contrata\u00e7\u00e3o: CLT<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Atividades:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Organizar o setor de sua responsabilidade no estoque;<\/li>\n<li>Manter a organiza\u00e7\u00e3o da loja: verificar se h\u00e1 produtos fora do lugar, repor os produtos nas araras\/expositores;<\/li>\n<li>Atender os clientes conforme as diretrizes informadas e aprendidas nos treinamentos oferecidos;<\/li>\n<li>Fazer, diariamente, o cadastro VIP de pelo menos 1 cliente, preenchendo corretamente o caderno destinado a tal finalidade; Contatar, via liga\u00e7\u00e3o ou mensagem no WhatsApp, os clientes cadastrados no caderno VIP informando-os sobre a chegada de novos produtos, promo\u00e7\u00f5es e convid\u00e1-los para vir \u00e0 loja; Contatar, via liga\u00e7\u00e3o ou mensagem no WhatsApp, os clientes aniversariantes do dia; Preencher a cada venda realizada a boleta, o cart\u00e3o de produ\u00e7\u00e3o e atualizar o valor da meta a ser alcan\u00e7ada no dia; Preencher, ao final do expediente, a planilha de produ\u00e7\u00e3o;<\/li>\n<li>Tirar falta das mercadorias recebidas; Auxiliar na limpeza da loja:<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de Trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Segunda \u00e0 S\u00e1bado<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Sal\u00e1rio:<\/p>\n<ul style=\"text-align: justify;\">\n<li>R$ 1.420,00<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Vale Transporte + Lanche + treinamentos + premia\u00e7\u00f5es<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Local: Copacabana \u2013 Rio de Janeiro<\/p>\n<p style=\"text-align: justify;\">Enviar curr\u00edculo informando no assunto do e-mail a vaga de interesse para <a href=\"mailto:rhmundodospes@gmail.com\">rhmundodospes@gmail.com <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Requisitos: Ensino m\u00e9dio; Experi\u00eancia em vendas; Ser\u00e1 um diferencial ter atuando do ramo do varejo; Facilidade de acesso \u00e0 regi\u00e3o. Contrata\u00e7\u00e3o: CLT Atividades: Organizar o [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,59],"tags":[],"class_list":["post-189305","post","type-post","status-publish","format-standard","hentry","category-comercial-vendedor","category-ensino-medio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vendedor \u2013 Copacabana -Rio de Janeiro - RJ - VagasRIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasrio.com.br\/index.php\/2024\/12\/05\/vendedor-copacabana-rio-de-janeiro-rj-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vendedor \u2013 Copacabana -Rio de Janeiro - RJ - VagasRIO\" \/>\n<meta property=\"og:description\" content=\"Requisitos: Ensino m\u00e9dio; Experi\u00eancia em vendas; Ser\u00e1 um diferencial ter atuando do ramo do varejo; Facilidade de acesso \u00e0 regi\u00e3o. Contrata\u00e7\u00e3o: CLT Atividades: Organizar o [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasrio.com.br\/index.php\/2024\/12\/05\/vendedor-copacabana-rio-de-janeiro-rj-2\/\" \/>\n<meta property=\"og:site_name\" content=\"VagasRIO\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-05T19:00:44+00:00\" \/>\n<meta name=\"author\" content=\"vagasemprego\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vagasemprego\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2024\\\/12\\\/05\\\/vendedor-copacabana-rio-de-janeiro-rj-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2024\\\/12\\\/05\\\/vendedor-copacabana-rio-de-janeiro-rj-2\\\/\"},\"author\":{\"name\":\"vagasemprego\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#\\\/schema\\\/person\\\/c11a3c03d007680d42e30222eff1ea53\"},\"headline\":\"Vendedor \u2013 Copacabana -Rio de Janeiro &#8211; RJ\",\"datePublished\":\"2024-12-05T19:00:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2024\\\/12\\\/05\\\/vendedor-copacabana-rio-de-janeiro-rj-2\\\/\"},\"wordCount\":214,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#organization\"},\"articleSection\":[\"comercial \\\/ vendas\",\"ensino m\u00e9dio\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2024\\\/12\\\/05\\\/vendedor-copacabana-rio-de-janeiro-rj-2\\\/\",\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2024\\\/12\\\/05\\\/vendedor-copacabana-rio-de-janeiro-rj-2\\\/\",\"name\":\"Vendedor \u2013 Copacabana -Rio de Janeiro - RJ - VagasRIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#website\"},\"datePublished\":\"2024-12-05T19:00:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2024\\\/12\\\/05\\\/vendedor-copacabana-rio-de-janeiro-rj-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2024\\\/12\\\/05\\\/vendedor-copacabana-rio-de-janeiro-rj-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2024\\\/12\\\/05\\\/vendedor-copacabana-rio-de-janeiro-rj-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasrio.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vendedor \u2013 Copacabana -Rio de Janeiro &#8211; RJ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/\",\"name\":\"VagasRIO\",\"description\":\"Vagas de Emprego e Est\u00e1gio no Rio de Janeiro\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasrio.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#organization\",\"name\":\"VagasRIO\",\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo90.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasrio.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo90.jpg\",\"width\":220,\"height\":90,\"caption\":\"VagasRIO\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#\\\/schema\\\/person\\\/c11a3c03d007680d42e30222eff1ea53\",\"name\":\"vagasemprego\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"vagasemprego\"},\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vendedor \u2013 Copacabana -Rio de Janeiro - RJ - VagasRIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/12\/05\/vendedor-copacabana-rio-de-janeiro-rj-2\/","og_locale":"pt_BR","og_type":"article","og_title":"Vendedor \u2013 Copacabana -Rio de Janeiro - RJ - VagasRIO","og_description":"Requisitos: Ensino m\u00e9dio; Experi\u00eancia em vendas; Ser\u00e1 um diferencial ter atuando do ramo do varejo; Facilidade de acesso \u00e0 regi\u00e3o. Contrata\u00e7\u00e3o: CLT Atividades: Organizar o [...]","og_url":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/12\/05\/vendedor-copacabana-rio-de-janeiro-rj-2\/","og_site_name":"VagasRIO","article_published_time":"2024-12-05T19:00:44+00:00","author":"vagasemprego","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vagasemprego","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/12\/05\/vendedor-copacabana-rio-de-janeiro-rj-2\/#article","isPartOf":{"@id":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/12\/05\/vendedor-copacabana-rio-de-janeiro-rj-2\/"},"author":{"name":"vagasemprego","@id":"https:\/\/www.vagasrio.com.br\/#\/schema\/person\/c11a3c03d007680d42e30222eff1ea53"},"headline":"Vendedor \u2013 Copacabana -Rio de Janeiro &#8211; RJ","datePublished":"2024-12-05T19:00:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/12\/05\/vendedor-copacabana-rio-de-janeiro-rj-2\/"},"wordCount":214,"publisher":{"@id":"https:\/\/www.vagasrio.com.br\/#organization"},"articleSection":["comercial \/ vendas","ensino m\u00e9dio"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/12\/05\/vendedor-copacabana-rio-de-janeiro-rj-2\/","url":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/12\/05\/vendedor-copacabana-rio-de-janeiro-rj-2\/","name":"Vendedor \u2013 Copacabana -Rio de Janeiro - RJ - VagasRIO","isPartOf":{"@id":"https:\/\/www.vagasrio.com.br\/#website"},"datePublished":"2024-12-05T19:00:44+00:00","breadcrumb":{"@id":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/12\/05\/vendedor-copacabana-rio-de-janeiro-rj-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasrio.com.br\/index.php\/2024\/12\/05\/vendedor-copacabana-rio-de-janeiro-rj-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasrio.com.br\/index.php\/2024\/12\/05\/vendedor-copacabana-rio-de-janeiro-rj-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasrio.com.br\/"},{"@type":"ListItem","position":2,"name":"Vendedor \u2013 Copacabana -Rio de Janeiro &#8211; RJ"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasrio.com.br\/#website","url":"https:\/\/www.vagasrio.com.br\/","name":"VagasRIO","description":"Vagas de Emprego e Est\u00e1gio no Rio de Janeiro","publisher":{"@id":"https:\/\/www.vagasrio.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasrio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasrio.com.br\/#organization","name":"VagasRIO","url":"https:\/\/www.vagasrio.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasrio.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasrio.com.br\/wp-content\/uploads\/2025\/06\/cropped-logo90.jpg","contentUrl":"https:\/\/www.vagasrio.com.br\/wp-content\/uploads\/2025\/06\/cropped-logo90.jpg","width":220,"height":90,"caption":"VagasRIO"},"image":{"@id":"https:\/\/www.vagasrio.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasrio.com.br\/#\/schema\/person\/c11a3c03d007680d42e30222eff1ea53","name":"vagasemprego","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"vagasemprego"},"url":"https:\/\/www.vagasrio.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/189305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=189305"}],"version-history":[{"count":0,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/189305\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=189305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=189305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=189305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}