{"id":191261,"date":"2025-06-09T15:00:19","date_gmt":"2025-06-09T18:00:19","guid":{"rendered":"https:\/\/www.vagasrio.com.br\/?p=191261"},"modified":"2025-06-08T17:01:19","modified_gmt":"2025-06-08T20:01:19","slug":"encarregado-de-estoque-deposito-rio-de-janeiro-rj-5","status":"publish","type":"post","link":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/09\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\/","title":{"rendered":"Encarregado de Estoque Dep\u00f3sito &#8211; Rio de Janeiro &#8211; RJ"},"content":{"rendered":"<p style=\"text-align: justify;\">Requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ensino M\u00e9dio Completo; Ensino Superior em Log\u00edstica \u00e9 um diferencial, mas n\u00e3o obrigat\u00f3rio.<\/li>\n<li>Necess\u00e1rio possuir experi\u00eancia na fun\u00e7\u00e3o no m\u00ednimo de 1 ano<\/li>\n<li>Desej\u00e1vel ter experi\u00eancia em lideran\u00e7a de equipes, bom racioc\u00ednio l\u00f3gico e afinidade com n\u00fameros.<\/li>\n<li>Contrata\u00e7\u00e3o: CLT<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Atividades:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Ser\u00e1 respons\u00e1vel em liderar e motivar a equipe de estoque, garantindo a organiza\u00e7\u00e3o e a efici\u00eancia no trabalho di\u00e1rio.<\/li>\n<li>Processos de Estoque: Manter o estoque organizado e eficiente. Garantir que as mercadorias estejam corretamente armazenadas e facilmente identific\u00e1veis. Confer\u00eancia de Produtos atrav\u00e9s de Notas Fiscais: Confer\u00eancia da entrada dos produtos no CD , atrav\u00e9s da NFE , garantindo o recebimento e armazenamento adequado dos produtos. Entrada e Sa\u00edda de Produtos: Gerenciar a entrada, separa\u00e7\u00e3o e sa\u00edda de produtos e materiais no dep\u00f3sito. Gest\u00e3o de Tarefas: Delegar fun\u00e7\u00f5es e gerenciar a execu\u00e7\u00e3o delas, assegurando a qualidade e as prioridades.<\/li>\n<li>Armazenagem de Produtos: Planejar e organizar a disposi\u00e7\u00e3o das mercadorias, facilitando sua identifica\u00e7\u00e3o, localiza\u00e7\u00e3o e manuseio.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Responsabilidade:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Limpeza e Organiza\u00e7\u00e3o: Manter o estoque limpo, organizado e arrumado, al\u00e9m de auxiliar nos processos de log\u00edstica.<br \/>\nInvent\u00e1rios: Acompanhar e responder pela equipe de contagem e invent\u00e1rios.<\/li>\n<li>Abertura e fechamento do dep\u00f3sito: Ter a responsabilidade de abertura e fechamento di\u00e1rio do dep\u00f3sito da empresa.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de Trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>44 horas semanais<\/li>\n<li>Segunda a Sexta Feira das 08:00 \u00e0s 17:30 ou 8:30 \u00e0s 18:00 e S\u00e1bado das 08:00 \u00e0s 12:00.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Sal\u00e1rio:<\/p>\n<ul style=\"text-align: justify;\">\n<li>R$ 2.100,00<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Vale Transporte; Refei\u00e7\u00e3o no Local; Plano Assim Sa\u00fade; Plano Odontol\u00f3gico; Aux\u00edlio Natalidade; Aux\u00edlio Funeral; Plano Adicional por Tempo Servi\u00e7o; Desconto nos produtos na loja da Costa Rica; Conv\u00eanio SESC<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Local de Trabalho: Rio de Janeiro, Penha.<\/p>\n<p style=\"text-align: justify;\">Enviar curr\u00edculo informando no assunto do e-mail a vaga de interesse para <a href=\"mailto:costaricacolchoes.curriculos@gmail.com\">costaricacolchoes.curriculos@gmail.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Requisitos: Ensino M\u00e9dio Completo; Ensino Superior em Log\u00edstica \u00e9 um diferencial, mas n\u00e3o obrigat\u00f3rio. Necess\u00e1rio possuir experi\u00eancia na fun\u00e7\u00e3o no m\u00ednimo de 1 ano Desej\u00e1vel [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59,61,69,85],"tags":[],"class_list":["post-191261","post","type-post","status-publish","format-standard","hentry","category-ensino-medio","category-ensino-superior","category-estoquista-almoxarife-auxiliar","category-logistica-transportes-motorista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Encarregado de Estoque Dep\u00f3sito - Rio de Janeiro - RJ - VagasRIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/09\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encarregado de Estoque Dep\u00f3sito - Rio de Janeiro - RJ - VagasRIO\" \/>\n<meta property=\"og:description\" content=\"Requisitos: Ensino M\u00e9dio Completo; Ensino Superior em Log\u00edstica \u00e9 um diferencial, mas n\u00e3o obrigat\u00f3rio. Necess\u00e1rio possuir experi\u00eancia na fun\u00e7\u00e3o no m\u00ednimo de 1 ano Desej\u00e1vel [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/09\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\/\" \/>\n<meta property=\"og:site_name\" content=\"VagasRIO\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-09T18:00:19+00:00\" \/>\n<meta name=\"author\" content=\"vagasemprego\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vagasemprego\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2025\\\/06\\\/09\\\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2025\\\/06\\\/09\\\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\\\/\"},\"author\":{\"name\":\"vagasemprego\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#\\\/schema\\\/person\\\/c11a3c03d007680d42e30222eff1ea53\"},\"headline\":\"Encarregado de Estoque Dep\u00f3sito &#8211; Rio de Janeiro &#8211; RJ\",\"datePublished\":\"2025-06-09T18:00:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2025\\\/06\\\/09\\\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\\\/\"},\"wordCount\":332,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#organization\"},\"articleSection\":[\"ensino m\u00e9dio\",\"ensino superior\",\"estoque \\\/ almoxarifado\",\"log\u00edstica \\\/ distribui\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2025\\\/06\\\/09\\\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\\\/\",\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2025\\\/06\\\/09\\\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\\\/\",\"name\":\"Encarregado de Estoque Dep\u00f3sito - Rio de Janeiro - RJ - VagasRIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#website\"},\"datePublished\":\"2025-06-09T18:00:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2025\\\/06\\\/09\\\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2025\\\/06\\\/09\\\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2025\\\/06\\\/09\\\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasrio.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encarregado de Estoque Dep\u00f3sito &#8211; Rio de Janeiro &#8211; RJ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/\",\"name\":\"VagasRIO\",\"description\":\"Vagas de Emprego e Est\u00e1gio no Rio de Janeiro\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasrio.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#organization\",\"name\":\"VagasRIO\",\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo90.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasrio.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo90.jpg\",\"width\":220,\"height\":90,\"caption\":\"VagasRIO\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#\\\/schema\\\/person\\\/c11a3c03d007680d42e30222eff1ea53\",\"name\":\"vagasemprego\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"vagasemprego\"},\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encarregado de Estoque Dep\u00f3sito - Rio de Janeiro - RJ - VagasRIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/09\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\/","og_locale":"pt_BR","og_type":"article","og_title":"Encarregado de Estoque Dep\u00f3sito - Rio de Janeiro - RJ - VagasRIO","og_description":"Requisitos: Ensino M\u00e9dio Completo; Ensino Superior em Log\u00edstica \u00e9 um diferencial, mas n\u00e3o obrigat\u00f3rio. Necess\u00e1rio possuir experi\u00eancia na fun\u00e7\u00e3o no m\u00ednimo de 1 ano Desej\u00e1vel [...]","og_url":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/09\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\/","og_site_name":"VagasRIO","article_published_time":"2025-06-09T18:00:19+00:00","author":"vagasemprego","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vagasemprego","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/09\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\/#article","isPartOf":{"@id":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/09\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\/"},"author":{"name":"vagasemprego","@id":"https:\/\/www.vagasrio.com.br\/#\/schema\/person\/c11a3c03d007680d42e30222eff1ea53"},"headline":"Encarregado de Estoque Dep\u00f3sito &#8211; Rio de Janeiro &#8211; RJ","datePublished":"2025-06-09T18:00:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/09\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\/"},"wordCount":332,"commentCount":0,"publisher":{"@id":"https:\/\/www.vagasrio.com.br\/#organization"},"articleSection":["ensino m\u00e9dio","ensino superior","estoque \/ almoxarifado","log\u00edstica \/ distribui\u00e7\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/09\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\/","url":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/09\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\/","name":"Encarregado de Estoque Dep\u00f3sito - Rio de Janeiro - RJ - VagasRIO","isPartOf":{"@id":"https:\/\/www.vagasrio.com.br\/#website"},"datePublished":"2025-06-09T18:00:19+00:00","breadcrumb":{"@id":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/09\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/09\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/09\/encarregado-de-estoque-deposito-rio-de-janeiro-rj-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasrio.com.br\/"},{"@type":"ListItem","position":2,"name":"Encarregado de Estoque Dep\u00f3sito &#8211; Rio de Janeiro &#8211; RJ"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasrio.com.br\/#website","url":"https:\/\/www.vagasrio.com.br\/","name":"VagasRIO","description":"Vagas de Emprego e Est\u00e1gio no Rio de Janeiro","publisher":{"@id":"https:\/\/www.vagasrio.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasrio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasrio.com.br\/#organization","name":"VagasRIO","url":"https:\/\/www.vagasrio.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasrio.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasrio.com.br\/wp-content\/uploads\/2025\/06\/cropped-logo90.jpg","contentUrl":"https:\/\/www.vagasrio.com.br\/wp-content\/uploads\/2025\/06\/cropped-logo90.jpg","width":220,"height":90,"caption":"VagasRIO"},"image":{"@id":"https:\/\/www.vagasrio.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasrio.com.br\/#\/schema\/person\/c11a3c03d007680d42e30222eff1ea53","name":"vagasemprego","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"vagasemprego"},"url":"https:\/\/www.vagasrio.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/191261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=191261"}],"version-history":[{"count":1,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/191261\/revisions"}],"predecessor-version":[{"id":191262,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/191261\/revisions\/191262"}],"wp:attachment":[{"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=191261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=191261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=191261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}