{"id":191417,"date":"2025-06-24T11:00:21","date_gmt":"2025-06-24T14:00:21","guid":{"rendered":"https:\/\/www.vagasrio.com.br\/?p=191417"},"modified":"2025-06-23T19:25:19","modified_gmt":"2025-06-23T22:25:19","slug":"cozinheira-rio-de-janeiro-rj","status":"publish","type":"post","link":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/24\/cozinheira-rio-de-janeiro-rj\/","title":{"rendered":"Cozinheira &#8211; Rio de Janeiro &#8211; RJ"},"content":{"rendered":"<p style=\"text-align: justify;\">Requisitos:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Disponibilidade de hor\u00e1rio;<\/li>\n<li>Alto astral, assiduidade, comprometimento com o trabalho e pontualidade;<\/li>\n<li>Higiene na prepara\u00e7\u00e3o dos alimentos;<\/li>\n<li>Criatividade na prepara\u00e7\u00e3o dos alimentos;<\/li>\n<li>Organiza\u00e7\u00e3o da cozinha;<\/li>\n<li>Limpeza das panelas e dos utens\u00edlios utilizados;<\/li>\n<li>Auxiliar na lou\u00e7a;<\/li>\n<li>Imprescind\u00edvel que more perto da empresa (Botafogo) ou lugar de fa\u00e7o acesso para chegar na empresa;<\/li>\n<li>Contrata\u00e7\u00e3o: CLT<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Descri\u00e7\u00e3o e Responsabilidades:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Precisamos de cozinheira pra cobrir as f\u00e9rias da atual cozinheira;<\/li>\n<li>Prepara\u00e7\u00e3o do alimento para as crian\u00e7as, funcionamento em escola;<\/li>\n<li>A atividade seria s\u00f3 pro m\u00eas de julho de 2025;<\/li>\n<li>Per\u00edodo de 6 horas de trabalho di\u00e1rio;<\/li>\n<li>In\u00edcio do trabalho \u00e0s 7:00;<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Jornada de Trabalho:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Segunda a Sexta Feira hor\u00e1rio a combinar<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Sal\u00e1rio:<\/p>\n<ul style=\"text-align: justify;\">\n<li>R$ 1.500,00<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Benef\u00edcios:<\/p>\n<ul style=\"text-align: justify;\">\n<li>VT<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Informa\u00e7\u00f5es adicionais:<\/p>\n<ul style=\"text-align: justify;\">\n<li>N\u00e3o oferecemos almo\u00e7o;<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Local: Botafogo \u2013 Rio de Janeiro<\/p>\n<p style=\"text-align: justify;\">Enviar curr\u00edculo informando no assunto do e-mail a vaga de interesse para <a href=\"mailto:liannabarra@yahoo.com.br\">liannabarra@yahoo.com.br<\/a><br \/>\nOu Enviar curr\u00edculo pelo WhatsApp 21 99052-0004<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Requisitos: Disponibilidade de hor\u00e1rio; Alto astral, assiduidade, comprometimento com o trabalho e pontualidade; Higiene na prepara\u00e7\u00e3o dos alimentos; Criatividade na prepara\u00e7\u00e3o dos alimentos; Organiza\u00e7\u00e3o da [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-191417","post","type-post","status-publish","format-standard","hentry","category-cozinheiro-garcom-chapeiro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cozinheira - Rio de Janeiro - RJ - VagasRIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/24\/cozinheira-rio-de-janeiro-rj\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cozinheira - Rio de Janeiro - RJ - VagasRIO\" \/>\n<meta property=\"og:description\" content=\"Requisitos: Disponibilidade de hor\u00e1rio; Alto astral, assiduidade, comprometimento com o trabalho e pontualidade; Higiene na prepara\u00e7\u00e3o dos alimentos; Criatividade na prepara\u00e7\u00e3o dos alimentos; Organiza\u00e7\u00e3o da [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/24\/cozinheira-rio-de-janeiro-rj\/\" \/>\n<meta property=\"og:site_name\" content=\"VagasRIO\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-24T14:00:21+00:00\" \/>\n<meta name=\"author\" content=\"vagasemprego\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vagasemprego\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2025\\\/06\\\/24\\\/cozinheira-rio-de-janeiro-rj\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2025\\\/06\\\/24\\\/cozinheira-rio-de-janeiro-rj\\\/\"},\"author\":{\"name\":\"vagasemprego\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#\\\/schema\\\/person\\\/c11a3c03d007680d42e30222eff1ea53\"},\"headline\":\"Cozinheira &#8211; Rio de Janeiro &#8211; RJ\",\"datePublished\":\"2025-06-24T14:00:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2025\\\/06\\\/24\\\/cozinheira-rio-de-janeiro-rj\\\/\"},\"wordCount\":173,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#organization\"},\"articleSection\":[\"alimenta\u00e7\u00e3o e gastronomia\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2025\\\/06\\\/24\\\/cozinheira-rio-de-janeiro-rj\\\/\",\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2025\\\/06\\\/24\\\/cozinheira-rio-de-janeiro-rj\\\/\",\"name\":\"Cozinheira - Rio de Janeiro - RJ - VagasRIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#website\"},\"datePublished\":\"2025-06-24T14:00:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2025\\\/06\\\/24\\\/cozinheira-rio-de-janeiro-rj\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2025\\\/06\\\/24\\\/cozinheira-rio-de-janeiro-rj\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/2025\\\/06\\\/24\\\/cozinheira-rio-de-janeiro-rj\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vagasrio.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cozinheira &#8211; Rio de Janeiro &#8211; RJ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#website\",\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/\",\"name\":\"VagasRIO\",\"description\":\"Vagas de Emprego e Est\u00e1gio no Rio de Janeiro\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vagasrio.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#organization\",\"name\":\"VagasRIO\",\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo90.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vagasrio.com.br\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/cropped-logo90.jpg\",\"width\":220,\"height\":90,\"caption\":\"VagasRIO\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vagasrio.com.br\\\/#\\\/schema\\\/person\\\/c11a3c03d007680d42e30222eff1ea53\",\"name\":\"vagasemprego\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g\",\"caption\":\"vagasemprego\"},\"url\":\"https:\\\/\\\/www.vagasrio.com.br\\\/index.php\\\/author\\\/vagasemprego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cozinheira - Rio de Janeiro - RJ - VagasRIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/24\/cozinheira-rio-de-janeiro-rj\/","og_locale":"pt_BR","og_type":"article","og_title":"Cozinheira - Rio de Janeiro - RJ - VagasRIO","og_description":"Requisitos: Disponibilidade de hor\u00e1rio; Alto astral, assiduidade, comprometimento com o trabalho e pontualidade; Higiene na prepara\u00e7\u00e3o dos alimentos; Criatividade na prepara\u00e7\u00e3o dos alimentos; Organiza\u00e7\u00e3o da [...]","og_url":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/24\/cozinheira-rio-de-janeiro-rj\/","og_site_name":"VagasRIO","article_published_time":"2025-06-24T14:00:21+00:00","author":"vagasemprego","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"vagasemprego","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/24\/cozinheira-rio-de-janeiro-rj\/#article","isPartOf":{"@id":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/24\/cozinheira-rio-de-janeiro-rj\/"},"author":{"name":"vagasemprego","@id":"https:\/\/www.vagasrio.com.br\/#\/schema\/person\/c11a3c03d007680d42e30222eff1ea53"},"headline":"Cozinheira &#8211; Rio de Janeiro &#8211; RJ","datePublished":"2025-06-24T14:00:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/24\/cozinheira-rio-de-janeiro-rj\/"},"wordCount":173,"commentCount":0,"publisher":{"@id":"https:\/\/www.vagasrio.com.br\/#organization"},"articleSection":["alimenta\u00e7\u00e3o e gastronomia"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/24\/cozinheira-rio-de-janeiro-rj\/","url":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/24\/cozinheira-rio-de-janeiro-rj\/","name":"Cozinheira - Rio de Janeiro - RJ - VagasRIO","isPartOf":{"@id":"https:\/\/www.vagasrio.com.br\/#website"},"datePublished":"2025-06-24T14:00:21+00:00","breadcrumb":{"@id":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/24\/cozinheira-rio-de-janeiro-rj\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/24\/cozinheira-rio-de-janeiro-rj\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vagasrio.com.br\/index.php\/2025\/06\/24\/cozinheira-rio-de-janeiro-rj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vagasrio.com.br\/"},{"@type":"ListItem","position":2,"name":"Cozinheira &#8211; Rio de Janeiro &#8211; RJ"}]},{"@type":"WebSite","@id":"https:\/\/www.vagasrio.com.br\/#website","url":"https:\/\/www.vagasrio.com.br\/","name":"VagasRIO","description":"Vagas de Emprego e Est\u00e1gio no Rio de Janeiro","publisher":{"@id":"https:\/\/www.vagasrio.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vagasrio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.vagasrio.com.br\/#organization","name":"VagasRIO","url":"https:\/\/www.vagasrio.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.vagasrio.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.vagasrio.com.br\/wp-content\/uploads\/2025\/06\/cropped-logo90.jpg","contentUrl":"https:\/\/www.vagasrio.com.br\/wp-content\/uploads\/2025\/06\/cropped-logo90.jpg","width":220,"height":90,"caption":"VagasRIO"},"image":{"@id":"https:\/\/www.vagasrio.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.vagasrio.com.br\/#\/schema\/person\/c11a3c03d007680d42e30222eff1ea53","name":"vagasemprego","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e198f9393383244894b06db503be8cb43011f384a429c7a9f84f3f61c138a35e?s=96&d=mm&r=g","caption":"vagasemprego"},"url":"https:\/\/www.vagasrio.com.br\/index.php\/author\/vagasemprego\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/191417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=191417"}],"version-history":[{"count":1,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/191417\/revisions"}],"predecessor-version":[{"id":191418,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/posts\/191417\/revisions\/191418"}],"wp:attachment":[{"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=191417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=191417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vagasrio.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=191417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}